{"id":4572,"date":"2023-04-10T09:03:24","date_gmt":"2023-04-10T08:03:24","guid":{"rendered":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/?p=4572"},"modified":"2023-04-10T09:03:24","modified_gmt":"2023-04-10T08:03:24","slug":"natuerlichen-pflanzenduenger-selbst-herstellen","status":"publish","type":"post","link":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/natuerlichen-pflanzenduenger-selbst-herstellen\/","title":{"rendered":"Nat\u00fcrlichen Pflanzend\u00fcnger selbst herstellen"},"content":{"rendered":"<p><span style=\"font-size: large;\"><span style=\"font-size: 14pt;\">Mein Hang zum DIY l\u00e4sst kaum einen Bereich des t\u00e4glichen Lebens aus. Da kommt eine Publikation mit dem Titel: \u201eNat\u00fcrlichen Pflanzend\u00fcnger selbst herstellen\u201c gerade recht. Nigel Palmer beschreibt in seinem Buch, wie man mit einfachen Mitteln D\u00fcnger in der eigenen K\u00fcche herstellen kann. Mit viel Hintergrundwissen erkl\u00e4rt er die Zusammenh\u00e4nge zwischen der Biologie im Boden und in der Pflanze. Weiter geht es mit Rezepten f\u00fcr mineralische und organische Zusatzstoffe. Die klar strukturierten Anleitungen behandeln die sp\u00e4tere Verwendung, von der Verd\u00fcnnung bis zur Lagerung. Wenn Sie glauben, ein Buch gekauft zu haben, das wie ein Kochbuch aufgebaut ist, werden Sie ein wenig entt\u00e4uscht sein. Tats\u00e4chlich muss man erst einmal 150 Seiten lesen, in denen die vielen Grundlagen behandelt werden, bevor man zum ersten Rezept kommt. Nach all dem einf\u00fchrenden Wissen erhalten wir Anleitung zur Bodenverbesserung mit Ausz\u00fcgen auf Wasserbasis. Weiter geht es mit der Herstellung von Apfelessig, der zur Gewinnung von Extrakten aus Eierschalen, Knochen, Meerestieren und so weiter verwendet wird. Es gibt nun eine Erkl\u00e4rung f\u00fcr die Fermentation von Pflanzen, Fischabf\u00e4llen und Blattkompost. Weiter geht es mit der Herstellung von Milchs\u00e4urebakterien. Dann ist mehr Aufwand erforderlich, bei der Kultivierung von einheimischen Mikroorganismen (IMO). Im letzten Teil zeigt uns eine Tabelle die Mineralstoffzus\u00e4tze in den einzelnen fermentierten Pflanzens\u00e4ften. Und eine Brix-Tabelle, die uns einen Einblick gibt, wie fit eine Pflanze ist.<\/span><\/span><\/p>\n<p><a href=\"https:\/\/www.narayana-verlag.de\/Natuerlichen-Pflanzenduenger-selbst-herstellen-Nigel-Palmer\/b28858\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4573 size-full\" src=\"https:\/\/www.kaktusmichel.de\/Kaktusnews\/wp-content\/uploads\/2023\/04\/Titelbild.jpg\" alt=\"\" width=\"560\" height=\"800\" srcset=\"https:\/\/www.kaktusmichel.de\/Kaktusnews\/wp-content\/uploads\/2023\/04\/Titelbild.jpg 560w, https:\/\/www.kaktusmichel.de\/Kaktusnews\/wp-content\/uploads\/2023\/04\/Titelbild-210x300.jpg 210w, https:\/\/www.kaktusmichel.de\/Kaktusnews\/wp-content\/uploads\/2023\/04\/Titelbild-105x150.jpg 105w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><br \/>\n<span style=\"font-size: 14pt;\"><em>Meine Meinung zum Buch:<\/em> <\/span><br \/>\n<span style=\"font-size: 14pt;\">Die 272 Seiten sind vollgepackt mit Grundlagenwissen und interessanten Denkanst\u00f6\u00dfen. Nigel Palmer hat in seinem Buch eine Menge Insiderwissen weitergegeben. Aber das Buch ist keine leichte Lekt\u00fcre, in denen mal schnell was braut, damit es den Kartoffeln besser geht. Einige Rezepte erfordern viel Zeit und Aufwand, insbesondere die Herstellung der von ihm am h\u00e4ufigsten verwendeten einheimischen Mikroorganismen. Es erfordert viel Willen und M\u00fche, einige der Rezepte zu befolgen, und nicht jeder hat gerne fermentierte Fischabf\u00e4lle in der K\u00fcche. <\/span><br \/>\n<span style=\"font-size: 14pt;\">Wenn diese Mittel wie beschrieben erfolgreich sind, ist das Buch der Schl\u00fcssel zu gesunden Pflanzen mit einem Vielfachen des N\u00e4hrwerts, den wir sonst erhalten k\u00f6nnen. Aber ich muss meine Skepsis noch \u00fcberwinden. <\/span><br \/>\n<span style=\"font-size: 14pt;\">Ich h\u00e4tte mir einen Ratgeber mit klarer definierten Rezepten f\u00fcr die einzelnen zu kultivierenden Pflanzen und weniger grundlegendem Lesestoff gew\u00fcnscht. Leserinnen und Leser, die alle Zusammenh\u00e4nge verstehen wollen, kommen aber auf jeden Fall auf ihre Kosten. <\/span><\/p>\n<p><em><span style=\"font-size: 14pt;\"><strong>Buch: <\/strong>272 Seiten, kart.<br \/>\n<strong>erschienen:<\/strong> 2023, von Unimedica im Narayana-Verlag<br \/>\n<strong>ISBN: <\/strong>978-3-96257-299-0<br \/>\n<b>Preis:<\/b> 22,80<\/span><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mein Hang zum DIY l\u00e4sst kaum einen Bereich des t\u00e4glichen Lebens aus. Da kommt eine Publikation mit dem Titel: \u201eNat\u00fcrlichen Pflanzend\u00fcnger selbst herstellen\u201c gerade recht. Nigel Palmer beschreibt in seinem &hellip; <\/p>\n","protected":false},"author":1,"featured_media":4574,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[352,367,16,142],"class_list":["post-4572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fur-sie-gelesen","tag-buch-rezenssion","tag-pflanzenduenger","tag-pflege","tag-rezension"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nat\u00fcrlichen Pflanzend\u00fcnger selbst herstellen - KAKTUSNEWS und andere Hobbys<\/title>\n<meta name=\"description\" content=\"Nigel Palmer beschreibt in seinem Buch, wie man mit einfachen Mitteln D\u00fcnger in der eigenen K\u00fcche herstellen kann.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kaktusmichel.de\/Kaktusnews\/natuerlichen-pflanzenduenger-selbst-herstellen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nat\u00fcrlichen Pflanzend\u00fcnger selbst herstellen - KAKTUSNEWS und andere Hobbys\" \/>\n<meta property=\"og:description\" content=\"Nigel Palmer beschreibt in seinem Buch, wie man mit einfachen Mitteln D\u00fcnger in der eigenen K\u00fcche herstellen kann.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kaktusmichel.de\/Kaktusnews\/natuerlichen-pflanzenduenger-selbst-herstellen\/\" \/>\n<meta property=\"og:site_name\" content=\"KAKTUSNEWS und andere Hobbys\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-10T08:03:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kaktusmichel.de\/Kaktusnews\/wp-content\/uploads\/2023\/04\/Banner.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"463\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Kaktusmichel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kaktusmichel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/natuerlichen-pflanzenduenger-selbst-herstellen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/natuerlichen-pflanzenduenger-selbst-herstellen\\\/\"},\"author\":{\"name\":\"Kaktusmichel\",\"@id\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/#\\\/schema\\\/person\\\/504467a53294f6fe26d2f94251972322\"},\"headline\":\"Nat\u00fcrlichen Pflanzend\u00fcnger selbst herstellen\",\"datePublished\":\"2023-04-10T08:03:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/natuerlichen-pflanzenduenger-selbst-herstellen\\\/\"},\"wordCount\":422,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/natuerlichen-pflanzenduenger-selbst-herstellen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Banner.jpg\",\"keywords\":[\"Buch rezenssion\",\"Pflanzend\u00fcnger\",\"Pflege\",\"Rezension\"],\"articleSection\":[\"F\u00fcr Sie gelesen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/natuerlichen-pflanzenduenger-selbst-herstellen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/natuerlichen-pflanzenduenger-selbst-herstellen\\\/\",\"url\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/natuerlichen-pflanzenduenger-selbst-herstellen\\\/\",\"name\":\"Nat\u00fcrlichen Pflanzend\u00fcnger selbst herstellen - KAKTUSNEWS und andere Hobbys\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/natuerlichen-pflanzenduenger-selbst-herstellen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/natuerlichen-pflanzenduenger-selbst-herstellen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Banner.jpg\",\"datePublished\":\"2023-04-10T08:03:24+00:00\",\"description\":\"Nigel Palmer beschreibt in seinem Buch, wie man mit einfachen Mitteln D\u00fcnger in der eigenen K\u00fcche herstellen kann.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/natuerlichen-pflanzenduenger-selbst-herstellen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/natuerlichen-pflanzenduenger-selbst-herstellen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/natuerlichen-pflanzenduenger-selbst-herstellen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Banner.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Banner.jpg\",\"width\":850,\"height\":463},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/natuerlichen-pflanzenduenger-selbst-herstellen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nat\u00fcrlichen Pflanzend\u00fcnger selbst herstellen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/#website\",\"url\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/\",\"name\":\"KAKTUSNEWS\",\"description\":\"Infos nicht nur \u00fcber Kakteen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/#organization\",\"name\":\"Andreae Kakteenkulturen\",\"url\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/Logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/Logo.jpg\",\"width\":140,\"height\":40,\"caption\":\"Andreae Kakteenkulturen\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kaktusmichel.de\\\/Kaktusnews\\\/#\\\/schema\\\/person\\\/504467a53294f6fe26d2f94251972322\",\"name\":\"Kaktusmichel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1d5f1c346518e6088098019cabba54da322625f761e5035e32bfcb531c421c1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1d5f1c346518e6088098019cabba54da322625f761e5035e32bfcb531c421c1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1d5f1c346518e6088098019cabba54da322625f761e5035e32bfcb531c421c1?s=96&d=mm&r=g\",\"caption\":\"Kaktusmichel\"},\"sameAs\":[\"http:\\\/\\\/www.kaktusmichel.de\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nat\u00fcrlichen Pflanzend\u00fcnger selbst herstellen - KAKTUSNEWS und andere Hobbys","description":"Nigel Palmer beschreibt in seinem Buch, wie man mit einfachen Mitteln D\u00fcnger in der eigenen K\u00fcche herstellen kann.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/natuerlichen-pflanzenduenger-selbst-herstellen\/","og_locale":"de_DE","og_type":"article","og_title":"Nat\u00fcrlichen Pflanzend\u00fcnger selbst herstellen - KAKTUSNEWS und andere Hobbys","og_description":"Nigel Palmer beschreibt in seinem Buch, wie man mit einfachen Mitteln D\u00fcnger in der eigenen K\u00fcche herstellen kann.","og_url":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/natuerlichen-pflanzenduenger-selbst-herstellen\/","og_site_name":"KAKTUSNEWS und andere Hobbys","article_published_time":"2023-04-10T08:03:24+00:00","og_image":[{"width":850,"height":463,"url":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/wp-content\/uploads\/2023\/04\/Banner.jpg","type":"image\/jpeg"}],"author":"Kaktusmichel","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Kaktusmichel","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/natuerlichen-pflanzenduenger-selbst-herstellen\/#article","isPartOf":{"@id":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/natuerlichen-pflanzenduenger-selbst-herstellen\/"},"author":{"name":"Kaktusmichel","@id":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/#\/schema\/person\/504467a53294f6fe26d2f94251972322"},"headline":"Nat\u00fcrlichen Pflanzend\u00fcnger selbst herstellen","datePublished":"2023-04-10T08:03:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/natuerlichen-pflanzenduenger-selbst-herstellen\/"},"wordCount":422,"commentCount":0,"publisher":{"@id":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/#organization"},"image":{"@id":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/natuerlichen-pflanzenduenger-selbst-herstellen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/wp-content\/uploads\/2023\/04\/Banner.jpg","keywords":["Buch rezenssion","Pflanzend\u00fcnger","Pflege","Rezension"],"articleSection":["F\u00fcr Sie gelesen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.kaktusmichel.de\/Kaktusnews\/natuerlichen-pflanzenduenger-selbst-herstellen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/natuerlichen-pflanzenduenger-selbst-herstellen\/","url":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/natuerlichen-pflanzenduenger-selbst-herstellen\/","name":"Nat\u00fcrlichen Pflanzend\u00fcnger selbst herstellen - KAKTUSNEWS und andere Hobbys","isPartOf":{"@id":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/natuerlichen-pflanzenduenger-selbst-herstellen\/#primaryimage"},"image":{"@id":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/natuerlichen-pflanzenduenger-selbst-herstellen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/wp-content\/uploads\/2023\/04\/Banner.jpg","datePublished":"2023-04-10T08:03:24+00:00","description":"Nigel Palmer beschreibt in seinem Buch, wie man mit einfachen Mitteln D\u00fcnger in der eigenen K\u00fcche herstellen kann.","breadcrumb":{"@id":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/natuerlichen-pflanzenduenger-selbst-herstellen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kaktusmichel.de\/Kaktusnews\/natuerlichen-pflanzenduenger-selbst-herstellen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/natuerlichen-pflanzenduenger-selbst-herstellen\/#primaryimage","url":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/wp-content\/uploads\/2023\/04\/Banner.jpg","contentUrl":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/wp-content\/uploads\/2023\/04\/Banner.jpg","width":850,"height":463},{"@type":"BreadcrumbList","@id":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/natuerlichen-pflanzenduenger-selbst-herstellen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/"},{"@type":"ListItem","position":2,"name":"Nat\u00fcrlichen Pflanzend\u00fcnger selbst herstellen"}]},{"@type":"WebSite","@id":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/#website","url":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/","name":"KAKTUSNEWS","description":"Infos nicht nur \u00fcber Kakteen","publisher":{"@id":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/#organization","name":"Andreae Kakteenkulturen","url":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/#\/schema\/logo\/image\/","url":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/wp-content\/uploads\/2018\/02\/Logo.jpg","contentUrl":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/wp-content\/uploads\/2018\/02\/Logo.jpg","width":140,"height":40,"caption":"Andreae Kakteenkulturen"},"image":{"@id":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/#\/schema\/person\/504467a53294f6fe26d2f94251972322","name":"Kaktusmichel","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f1d5f1c346518e6088098019cabba54da322625f761e5035e32bfcb531c421c1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f1d5f1c346518e6088098019cabba54da322625f761e5035e32bfcb531c421c1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f1d5f1c346518e6088098019cabba54da322625f761e5035e32bfcb531c421c1?s=96&d=mm&r=g","caption":"Kaktusmichel"},"sameAs":["http:\/\/www.kaktusmichel.de"]}]}},"_links":{"self":[{"href":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/wp-json\/wp\/v2\/posts\/4572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/wp-json\/wp\/v2\/comments?post=4572"}],"version-history":[{"count":2,"href":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/wp-json\/wp\/v2\/posts\/4572\/revisions"}],"predecessor-version":[{"id":4576,"href":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/wp-json\/wp\/v2\/posts\/4572\/revisions\/4576"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/wp-json\/wp\/v2\/media\/4574"}],"wp:attachment":[{"href":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/wp-json\/wp\/v2\/media?parent=4572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/wp-json\/wp\/v2\/categories?post=4572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kaktusmichel.de\/Kaktusnews\/wp-json\/wp\/v2\/tags?post=4572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}